{"id":18,"count":3,"description":"","link":"https:\/\/deals-here.com\/fredemailcrashcourse.com\/category\/leads\/","name":"Leads","slug":"leads","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/deals-here.com\/fredemailcrashcourse.com\/wp-json\/wp\/v2\/categories\/18","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/deals-here.com\/fredemailcrashcourse.com\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/deals-here.com\/fredemailcrashcourse.com\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/deals-here.com\/fredemailcrashcourse.com\/wp-json\/wp\/v2\/posts?categories=18"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}